{"id":66581,"date":"2025-03-19T08:45:14","date_gmt":"2025-03-19T08:45:14","guid":{"rendered":"https:\/\/www.achilles.com\/achilles-faz-parceria-com-a-complyadvantage-para-integrar-o-adverse-media-screening-em-sua-plataforma-de-gerenciamento-de-riscos\/"},"modified":"2025-03-20T11:24:15","modified_gmt":"2025-03-20T11:24:15","slug":"achilles-faz-parceria-com-a-complyadvantage-para-integrar-o-adverse-media-screening-em-sua-plataforma-de-gerenciamento-de-riscos","status":"publish","type":"post","link":"https:\/\/www.achilles.com\/pt-br\/industry-insights\/achilles-faz-parceria-com-a-complyadvantage-para-integrar-o-adverse-media-screening-em-sua-plataforma-de-gerenciamento-de-riscos\/","title":{"rendered":"Achilles faz parceria com a ComplyAdvantage para integrar o Adverse Media Screening em sua plataforma de gerenciamento de riscos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>A nova solu\u00e7\u00e3o ajudar\u00e1 as empresas a identificar riscos regulat\u00f3rios, de reputa\u00e7\u00e3o e financeiros de seus fornecedores, permitindo que tomem decis\u00f5es mais informadas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABINGDON, Reino Unido, MAR\u00c7O DE 2025 &#8211; A Achilles, l\u00edder global em gest\u00e3o de cadeia de suprimentos e desempenho, uniu for\u00e7as com a ComplyAdvantage, fornecedora l\u00edder de detec\u00e7\u00e3o de riscos orientada por IA, para integrar o Adverse Media Screening em sua plataforma global de gest\u00e3o de riscos da cadeia de suprimentos. Essa nova solu\u00e7\u00e3o permite que as empresas identifiquem riscos regulat\u00f3rios, de reputa\u00e7\u00e3o e financeiros associados a seus fornecedores, possibilitando uma tomada de decis\u00e3o mais informada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A associa\u00e7\u00e3o com fornecedores que t\u00eam cobertura negativa da m\u00eddia pode prejudicar a reputa\u00e7\u00e3o de uma empresa, levar a perdas financeiras e a um escrut\u00ednio legal. Para reduzir esses riscos, a Achilles introduziu o Adverse Media Screening em sua plataforma de gerenciamento de riscos. Esse aprimoramento permite que as organiza\u00e7\u00f5es identifiquem fornecedores envolvidos em pr\u00e1ticas anti\u00e9ticas, protejam sua marca e mantenham a confian\u00e7a dos clientes e das partes interessadas.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nova ferramenta de M\u00eddia Adversa da Achilles oferece uma camada adicional de detec\u00e7\u00e3o de riscos, examinando mais de 2 milh\u00f5es de artigos por dia de fontes verificadas. Ela identifica not\u00edcias negativas sobre fornecedores globais, incluindo quest\u00f5es regulat\u00f3rias, riscos de reputa\u00e7\u00e3o e preocupa\u00e7\u00f5es financeiras. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com cobertura em sete idiomas &#8211; espanhol, portugu\u00eas, italiano, franc\u00eas, alem\u00e3o, holand\u00eas e ingl\u00eas &#8211; a ferramenta analisa uma ampla gama de fontes, incluindo os principais ve\u00edculos de not\u00edcias, blogs do setor, jornais locais e sites governamentais. Ao monitorar e traduzir o conte\u00fado global, o Achilles oferece percep\u00e7\u00f5es abrangentes sobre os riscos potenciais de diversas fontes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Em um mundo em que as not\u00edcias negativas se espalham mais r\u00e1pido do que nunca, as empresas precisam adotar uma abordagem proativa para o gerenciamento de riscos. A solu\u00e7\u00e3o de Triagem de M\u00eddia Adversa da Achilles permite que as organiza\u00e7\u00f5es fiquem \u00e0 frente de amea\u00e7as potenciais, identificando riscos antecipadamente, em v\u00e1rios idiomas e fontes. Com a parceria com a ComplyAdvantage, reunimos tecnologia de IA l\u00edder mundial e experi\u00eancia no setor para oferecer \u00e0s empresas uma maneira escal\u00e1vel e eficaz de proteger suas cadeias de suprimentos&#8221;, <\/em>disse Mark Chamberlain, diretor de produtos da Achilles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Achilles Adverse Media Screening est\u00e1 dispon\u00edvel para os clientes compradores da Achilles por meio da plataforma Achilles. As organiza\u00e7\u00f5es interessadas em explorar a nova solu\u00e7\u00e3o podem solicitar uma demonstra\u00e7\u00e3o <strong><u><a href=\"https:\/\/www.achilles.com\/pt-br\/contate-nos\/\">aqui<\/a><\/u><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contato com a imprensa<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Roc\u00edo Artacho, gerente de marketing de produto  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:rocio.artacho@achilles.com\" target=\"_blank\" rel=\"noreferrer noopener\">rocio.artacho@achilles.com<\/a>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre o ComplyAdvantage<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ComplyAdvantage \u00e9 uma empresa l\u00edder em RegTech fundada em 2014 por Charles Delingpole, especializada em tecnologia de detec\u00e7\u00e3o e dados de risco de crimes financeiros orientados por IA. A empresa oferece solu\u00e7\u00f5es para integra\u00e7\u00e3o e monitoramento de combate \u00e0 lavagem de dinheiro (AML), monitoramento de transa\u00e7\u00f5es, triagem de pagamentos e triagem de m\u00eddia adversa, atendendo a mais de 1.600 empresas em 75 pa\u00edses. Ao aproveitar o aprendizado de m\u00e1quina e o processamento de linguagem natural, o ComplyAdvantage fornece informa\u00e7\u00f5es em tempo real sobre san\u00e7\u00f5es, listas de observa\u00e7\u00e3o, pessoas politicamente expostas (PEPs) e not\u00edcias negativas, ajudando as organiza\u00e7\u00f5es a gerenciar riscos e combater crimes financeiros com efici\u00eancia. A empresa estabeleceu centros globais em Nova York, Londres, Cingapura e Cluj-Napoca.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/complyadvantage.com\/\" data-type=\"link\" data-id=\"https:\/\/complyadvantage.com\/\">www.complyadvantage.com<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre Achilles<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 mais de 30 anos, a Achilles protege os interesses comerciais e a reputa\u00e7\u00e3o das organiza\u00e7\u00f5es, oferecendo n\u00edveis incompar\u00e1veis de transpar\u00eancia da cadeia de suprimentos, redu\u00e7\u00e3o e gerenciamento de carbono. A Achilles \u00e9 a parceira de gest\u00e3o de carbono e ESG preferida das principais marcas globais do mundo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Achilles \u00e9 especializada no apoio a clientes que necessitam de relat\u00f3rios ambientais, sociais e de governa\u00e7\u00e3o verdadeiramente s\u00f3lidos para cumprir integralmente a regulamenta\u00e7\u00e3o ESG, satisfazer os requisitos dos investidores e atingir os seus pr\u00f3prios objectivos ambiciosos em mat\u00e9ria de sustentabilidade. A empresa trabalha com organiza\u00e7\u00f5es financeiras, industriais, comerciais e governamentais l\u00edderes de mercado que precisam de an\u00e1lises s\u00e9rias e detalhadas e da percep\u00e7\u00e3o especializada necess\u00e1ria para oferecer uma sele\u00e7\u00e3o excepcional de fornecedores e confian\u00e7a nos relat\u00f3rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Operando em 19 locais em todo o mundo, a Achilles est\u00e1 na vanguarda da batalha contra as mudan\u00e7as clim\u00e1ticas, \u00e9 defensora da justi\u00e7a social e dos direitos humanos e especialista em sa\u00fade, seguran\u00e7a e gerenciamento de riscos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.achilles.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.achilles.com<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nova solu\u00e7\u00e3o ajudar\u00e1 as empresas a identificar riscos regulat\u00f3rios, de reputa\u00e7\u00e3o e financeiros de seus fornecedores, permitindo que tomem decis\u00f5es mais informadas. ABINGDON, Reino Unido, MAR\u00c7O DE 2025 &#8211; A Achilles, l\u00edder global em gest\u00e3o de cadeia de suprimentos e desempenho, uniu for\u00e7as com a ComplyAdvantage, fornecedora l\u00edder de detec\u00e7\u00e3o de riscos orientada por [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":66318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","wds_primary_category":3962,"wds_primary_industry_tax":0,"wds_primary_topic_tax":0,"wds_primary_post_region_tax":0,"footnotes":""},"categories":[3962,8779,4298,12027],"tags":[11047,11048,11049],"industry_tax":[4299],"topic_tax":[4361,4031],"post_region_tax":[12423,12425,12424,12427,12426],"class_list":["post-66581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-pt-br","category-atualizacoes-do-produto","category-comunicado-de-imprensa","category-informacoes-setoriais","tag-cumprir-a-vantagem","tag-midia-adversa","tag-triagem-de-midia","industry_tax-todos","topic_tax-conformidade-e-legislacao-pt-br","topic_tax-sustentabilidade-pt-br","post_region_tax-ingles-au","post_region_tax-ingles-eua","post_region_tax-ingles-in","post_region_tax-ingles-mea","post_region_tax-ingles-uki"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts\/66581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/comments?post=66581"}],"version-history":[{"count":0,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts\/66581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/media\/66318"}],"wp:attachment":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/media?parent=66581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/categories?post=66581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/tags?post=66581"},{"taxonomy":"industry_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/industry_tax?post=66581"},{"taxonomy":"topic_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/topic_tax?post=66581"},{"taxonomy":"post_region_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/post_region_tax?post=66581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}