{"id":50843,"date":"2024-10-02T11:47:29","date_gmt":"2024-10-02T10:47:29","guid":{"rendered":"https:\/\/www.achilles.com\/como-o-modulo-de-conformidade-iogp-423-aprimorado-da-achilles-esta-ajudando-as-empresas-de-energia-a-atingir-padroes-mais-elevados-de-hse\/"},"modified":"2025-07-22T19:26:04","modified_gmt":"2025-07-22T18:26:04","slug":"como-o-modulo-de-conformidade-iogp-423-aprimorado-da-achilles-esta-ajudando-as-empresas-de-energia-a-atingir-padroes-mais-elevados-de-hse","status":"publish","type":"post","link":"https:\/\/www.achilles.com\/pt-br\/industry-insights\/como-o-modulo-de-conformidade-iogp-423-aprimorado-da-achilles-esta-ajudando-as-empresas-de-energia-a-atingir-padroes-mais-elevados-de-hse\/","title":{"rendered":"Como o M\u00f3dulo de Conformidade IOGP 423 aprimorado da Achilles est\u00e1 ajudando as empresas de energia a atingir padr\u00f5es mais elevados de HSE"},"content":{"rendered":"\n<p>A Associa\u00e7\u00e3o Internacional de Produtores de Petr\u00f3leo e G\u00e1s (IOGP) 423 (<a href=\"https:\/\/www.iogp.org\/bookstore\/product\/report-423-hse-management-guidelines-for-working-together-in-a-contract-environment-info-sheets\/#:~:text=Report%20423%20%E2%80%93%20HSE%20management%20guidelines,a%20contract%20environment%20%E2%80%93%20Info%20Sheets\"><strong>Diretrizes de gerenciamento de HSE para trabalho conjunto em um ambiente de contrato)<\/strong><\/a> tem sido, h\u00e1 muito tempo, a refer\u00eancia em rela\u00e7\u00e3o \u00e0 qual as empresas de petr\u00f3leo e g\u00e1s medem a melhoria do desempenho em seguran\u00e7a.\nEmbora seja um conjunto de boas pr\u00e1ticas de HSE altamente \u00fatil e sensato, n\u00e3o h\u00e1 d\u00favida de que trabalhar de acordo com as diretrizes em ambientes globais de petr\u00f3leo e g\u00e1s fragmentados, remotos e de alto risco \u00e9 exigente at\u00e9 mesmo para o profissional de HSE mais experiente. <\/p>\n\n<p>Mas h\u00e1 uma maneira mais f\u00e1cil.\nE ela vem na forma do rec\u00e9m-aprimorado <a href=\"https:\/\/www.achilles.com\/industry-insights\/achilles-launches-major-update-to-meet-iogp-423-guidelines\/\" data-type=\"link\" data-id=\"https:\/\/www.achilles.com\/industry-insights\/achilles-launches-major-update-to-meet-iogp-423-guidelines\/\">M\u00f3dulo de Conformidade IOGP<\/a> da Achilles.\nO m\u00f3dulo IOGP da Achilles ganhou popularidade nos \u00faltimos anos devido ao seu alinhamento abrangente com todos os aspectos das diretrizes da IOGP e \u00e0 sua capacidade de dar suporte \u00e0s empresas de energia em n\u00edvel global (e n\u00e3o nacional).  <\/p>\n\n<p>Com sua abordagem em n\u00edveis para o gerenciamento de fornecedores com base em categorias de produtos e servi\u00e7os (de baixo risco a alto risco), autoavalia\u00e7\u00e3o de fornecedores e auditoria de fornecedores e subcontratados, ele oferece uma solu\u00e7\u00e3o hol\u00edstica que \u00e9 eficiente e econ\u00f4mica.\nCom os aprimoramentos mais recentes do m\u00f3dulo, agora \u00e9 uma \u00f3tima oportunidade para as empresas que ainda est\u00e3o usando solu\u00e7\u00f5es locais ou menos abrangentes darem uma nova olhada. <\/p>\n\n<p>Neste artigo, analisamos os aprimoramentos da \u00faltima vers\u00e3o do m\u00f3dulo IOGP Compliance.\nPara agendar uma demonstra\u00e7\u00e3o sem compromisso, entre em contato preenchendo o formul\u00e1rio abaixo. <\/p>\n\n<h2 class=\"wp-block-heading\">\n          <strong>Avalia\u00e7\u00e3o hol\u00edstica<\/strong>\n        <\/h2>\n\n<p>O m\u00f3dulo de conformidade com a IOGP da Achilles permite que as empresas de petr\u00f3leo e g\u00e1s adotem uma abordagem hol\u00edstica baseada em riscos para o gerenciamento de contratados.\nEle inclui valida\u00e7\u00e3o de dados de empreiteiros independentes, auditoria de desktop e no local sobre diretrizes e padr\u00f5es de HSE &#8211; adequados para categorias de produtos classificadas como de alto risco pela IOGP.\nTamb\u00e9m oferece suporte \u00e0 cria\u00e7\u00e3o de redes entre as partes, relat\u00f3rios de incidentes, prepara\u00e7\u00e3o para emerg\u00eancias, treinamento e conformidade regulamentar.  <\/p>\n\n<h2 class=\"wp-block-heading\">\n          <strong>M\u00f3dulo aprimorado de autoavalia\u00e7\u00e3o de contratados da IOGP<\/strong>\n        <\/h2>\n\n<p>O m\u00f3dulo IOGP agora inclui um question\u00e1rio aprimorado de autoavalia\u00e7\u00e3o do contratante IOGP que est\u00e1 totalmente alinhado com as Diretrizes IOGP 423.\nO question\u00e1rio conduz as organiza\u00e7\u00f5es contratantes pelo processo necess\u00e1rio para avaliar e medir seus pr\u00f3prios sistemas, pr\u00e1ticas e desempenho de gerenciamento de HSE.\nEle tamb\u00e9m fornece simultaneamente um conjunto completo de dados de fornecedores e contratados para permitir que as organiza\u00e7\u00f5es compradoras de petr\u00f3leo e g\u00e1s rastreiem e me\u00e7am o desempenho da cadeia de suprimentos em todo o conjunto de categorias de HSE da IOGP 423.  <\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"281\" src=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-1.png\" alt=\"\" class=\"wp-image-50487\" srcset=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-1.png 870w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-1-300x97.png 300w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-1-768x248.png 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<h2 class=\"wp-block-heading\">\n          <strong>Melhoria cont\u00ednua<\/strong>\n        <\/h2>\n\n<p>As empresas do setor de petr\u00f3leo e g\u00e1s agora podem avaliar de forma f\u00e1cil e eficiente o alinhamento de fornecedores e contratados com os requisitos da IOGP por meio da pontua\u00e7\u00e3o da IOGP da Achilles (de 260 pontos).\nEssas pontua\u00e7\u00f5es e pain\u00e9is de controle permitem que as empresas do setor de petr\u00f3leo e g\u00e1s identifiquem rapidamente os riscos e as oportunidades de melhoria e avaliem a si mesmas e aos outros em rela\u00e7\u00e3o aos crit\u00e9rios acordados em todo o setor.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" data-id=\"50537\" src=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview-1024x528.png\" alt=\"\" class=\"wp-image-50537\" srcset=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview-1024x528.png 1024w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview-300x155.png 300w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview-768x396.png 768w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview-1536x793.png 1536w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Score-overview.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"466\" data-id=\"50507\" src=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-3.png\" alt=\"\" class=\"wp-image-50507\" srcset=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-3.png 752w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/IOGP-3-300x186.png 300w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><\/figure><\/figure>\n\n<h2 class=\"wp-block-heading\">\n          <strong>Relat\u00f3rios mais f\u00e1ceis<\/strong>\n        <\/h2>\n\n<p>Agora, as empresas de petr\u00f3leo e g\u00e1s podem usar os relat\u00f3rios da Achilles com mais facilidade para divulgar informa\u00e7\u00f5es \u00e0s partes interessadas dentro e fora da plataforma MyAchilles por meio do Achilles Analytics, promovendo transpar\u00eancia, aprimoramento e, o mais importante, percep\u00e7\u00f5es acion\u00e1veis para aprimorar e melhorar o desempenho da seguran\u00e7a.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"350\" src=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1-1024x350.png\" alt=\"\" class=\"wp-image-50557\" srcset=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1-1024x350.png 1024w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1-300x103.png 300w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1-768x263.png 768w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1-1536x525.png 1536w, https:\/\/www.achilles.com\/app\/uploads\/2024\/10\/AC1532-MyAchilles-IOGP-screenshot-Quicklist-1.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<h2 class=\"wp-block-heading\"><strong>Junte-se \u00e0 Rede Global de Energia da Achilles<\/strong> <strong>para melhorar a gest\u00e3o de SMS<\/strong><\/h2>\n\n<p>O M\u00f3dulo de Conformidade da IOGP est\u00e1 dispon\u00edvel por meio da <a href=\"https:\/\/www.achilles.com\/pt-br\/global-energy-2\/\">Rede Global de Energia<\/a> da <a href=\"https:\/\/www.achilles.com\/pt-br\/global-energy-2\/\">Achilles<\/a> na <a href=\"https:\/\/www.achilles.com\/pt-br\/my-achilles\/\">plataforma MyAchilles<\/a>, que conecta os principais compradores de energia com os fornecedores, permitindo que as empresas demonstrem claramente sua conformidade com uma ampla gama de requisitos e normas regulat\u00f3rias espec\u00edficas, como a NORSOK S006 e a IOGP.<\/p>\n\n<p>A partir de um question\u00e1rio r\u00e1pido sobre as principais informa\u00e7\u00f5es da empresa e os produtos e servi\u00e7os que ela oferece, a Rede de Energia Achilles permite que as empresas demonstrem que atendem aos requisitos das organiza\u00e7\u00f5es compradoras atuais e potenciais e, mais especificamente, \u00e0s diretrizes da IOGP, facilitando a obten\u00e7\u00e3o de padr\u00f5es de HSE e promovendo a melhoria cont\u00ednua.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Internacional de Produtores de Petr\u00f3leo e G\u00e1s (IOGP) 423 (Diretrizes de gerenciamento de HSE para trabalho conjunto em um ambiente de contrato) tem sido, h\u00e1 muito tempo, a refer\u00eancia em rela\u00e7\u00e3o \u00e0 qual as empresas de petr\u00f3leo e g\u00e1s medem a melhoria do desempenho em seguran\u00e7a. Embora seja um conjunto de boas pr\u00e1ticas [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":13031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","wds_primary_category":0,"wds_primary_industry_tax":0,"wds_primary_topic_tax":0,"wds_primary_post_region_tax":0,"footnotes":""},"categories":[8779,12027],"tags":[10162,10161],"industry_tax":[4153,4299],"topic_tax":[4030,4361,4360],"post_region_tax":[],"class_list":["post-50843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualizacoes-do-produto","category-informacoes-setoriais","tag-conformidade-com-o-iogp","tag-gerenciamento-de-hse","industry_tax-energy-pt-br","industry_tax-todos","topic_tax-cadeia-de-suprimentos-pt-br","topic_tax-conformidade-e-legislacao-pt-br","topic_tax-salud-y-seguridad-pt-br"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts\/50843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/comments?post=50843"}],"version-history":[{"count":0,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/posts\/50843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/media\/13031"}],"wp:attachment":[{"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/media?parent=50843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/categories?post=50843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/tags?post=50843"},{"taxonomy":"industry_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/industry_tax?post=50843"},{"taxonomy":"topic_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/topic_tax?post=50843"},{"taxonomy":"post_region_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/pt-br\/wp-json\/wp\/v2\/post_region_tax?post=50843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}