{"id":40553,"date":"2024-04-23T11:20:58","date_gmt":"2024-04-23T08:20:58","guid":{"rendered":"https:\/\/www.achilles.com\/introducing-the-achilles-carbon-calculator-simplifying-ghg-emissions-management-for-businesses\/"},"modified":"2024-04-26T16:40:37","modified_gmt":"2024-04-26T13:40:37","slug":"introducing-the-achilles-carbon-calculator-simplifying-ghg-emissions-management-for-businesses","status":"publish","type":"post","link":"https:\/\/www.achilles.com\/fr\/informations-sectorielles\/calculateur-dempreinte-carbone\/","title":{"rendered":"Voici le Calculateur de Carbone Achilles : Simplifiant la Gestion des \u00c9missions de GES pour les Entreprises"},"content":{"rendered":"\n<p><strong>L&#8217;\u00e9quipe ici chez Achilles est ravie de pr\u00e9senter la derni\u00e8re fonctionnalit\u00e9 dans <a href=\"https:\/\/www.achilles.com\/industry-insights\/introducing-the-carbon-module\/\">le Module de Gestion du Carbone<\/a> MyAchilles &#8211; le Calculateur de Carbone Achilles. Notre nouvel outil de Calculateur de Carbone est con\u00e7u pour permettre aux organisations de capturer leurs donn\u00e9es d&#8217;\u00e9missions de gaz \u00e0 effet de serre (GES) et de les partager avec leurs clients &#8211; de mani\u00e8re tr\u00e8s simple et tr\u00e8s rentable.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"496\" src=\"https:\/\/www.achilles.com\/wp\/wp-content\/uploads\/2024\/04\/AC1420-Emissions-data-graphic-1024x496.png\" alt=\"\" class=\"wp-image-40322 size-full\" srcset=\"https:\/\/www.achilles.com\/app\/uploads\/2024\/04\/AC1420-Emissions-data-graphic-1024x496.png 1024w, https:\/\/www.achilles.com\/app\/uploads\/2024\/04\/AC1420-Emissions-data-graphic-300x145.png 300w, https:\/\/www.achilles.com\/app\/uploads\/2024\/04\/AC1420-Emissions-data-graphic-768x372.png 768w, https:\/\/www.achilles.com\/app\/uploads\/2024\/04\/AC1420-Emissions-data-graphic-1536x744.png 1536w, https:\/\/www.achilles.com\/app\/uploads\/2024\/04\/AC1420-Emissions-data-graphic.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Cet nouvel outil est principalement destin\u00e9 aux entreprises qui se trouvent aux premiers stades de mesure de leur empreinte carbone et qui ne collectent pas encore de donn\u00e9es sur les GES, ou qui se sont appuy\u00e9es sur des feuilles de calcul Excel pour le faire et sont maintenant pr\u00eates \u00e0 adopter une solution plus professionnelle et plus efficace.<\/p>\n<\/div><\/div>\n\n\n\n<p>N&#8217;oubliez pas, Achilles propose \u00e9galement d&#8217;autres services de gestion du carbone tels que <a href=\"https:\/\/www.achilles.com\/fr\/reduction-de-carbone\/\">Carbon Reduce<\/a> pour les organisations plus avanc\u00e9es dans leur parcours carbone, pr\u00eates \u00e0 r\u00e9aliser des r\u00e9ductions significatives d&#8217;\u00e9missions de carbone et \u00e0 rechercher une solution audit\u00e9e de mani\u00e8re ind\u00e9pendante.<\/p>\n\n\n\n<p>Le Calculateur de Carbone utilise un ensemble complet de questions pour vous guider dans le processus de saisie de toutes les donn\u00e9es brutes d&#8217;\u00e9missions dont vous avez besoin pour capturer, telles que l&#8217;utilisation d&#8217;essence et la consommation d&#8217;\u00e9lectricit\u00e9. Il calcule ensuite vos \u00e9missions de carbone pour vous en utilisant des algorithmes \u00e9tablis et reconnus internationalement. En savoir plus sur le <a href=\"https:\/\/ghgprotocol.org\/\">Protocole des Gaz \u00e0 Effet de Serre.<\/a><\/p>\n\n\n\n<p>Il est de plus en plus important pour les entreprises de toutes tailles de comprendre leurs \u00e9missions. Outre l&#8217;importance \u00e9vidente de travailler tous ensemble pour r\u00e9duire les \u00e9missions et de jouer notre r\u00f4le pour atteindre z\u00e9ro \u00e9mission nette, les \u00e9missions de carbone deviennent \u00e9galement un facteur important dans les d\u00e9cisions d&#8217;approvisionnement. Les grandes entreprises sont de plus en plus sous pression pour capturer <a href=\"https:\/\/www.achilles.com\/industry-insights\/what-are-scope-3-emissions\/\">leurs \u00e9missions indirectes de la &#8220;Port\u00e9e 3&#8221; de leur cha\u00eene d&#8217;approvisionnement<\/a> afin de se conformer \u00e0 des r\u00e9glementations telles que le <a href=\"https:\/\/www.achilles.com\/fr\/directive-devoir-vigilance-entreprises-matiere-durabilite\/\">CSDDD<\/a> et <a href=\"https:\/\/www.achilles.com\/industry-insights\/what-does-ifrss-take-over-from-tcfd-mean-for-uk-businesses\/\">l&#8217;IFRS<\/a>, et ont besoin de ces informations de la part de leurs fournisseurs pour le faire.<\/p>\n\n\n\n<p>Les acheteurs veulent \u00e9galement ces informations afin de pouvoir prendre des d\u00e9cisions d&#8217;approvisionnement plus \u00e9clair\u00e9es et de s\u00e9lectionner des fournisseurs ayant des empreintes environnementales plus faibles et\/ou qui peuvent montrer qu&#8217;ils travaillent \u00e0 r\u00e9duire les \u00e9missions pour aider \u00e0 atteindre leurs objectifs de durabilit\u00e9 plus larges. Pour rendre cela aussi simple que possible, les donn\u00e9es de carbone collect\u00e9es dans le Calculateur de Carbone sont automatiquement ajout\u00e9es au profil de chaque entreprise dans MyAchilles et peuvent \u00e9galement \u00eatre facilement export\u00e9es pour \u00eatre incluses dans vos propositions, appels d&#8217;offres et processus d&#8217;ench\u00e8res.<\/p>\n\n\n\n<p>Dans l&#8217;ensemble, le nouveau Calculateur de Carbone Achilles est l\u00e0 pour aider les entreprises \u00e0 d\u00e9marrer de mani\u00e8re fluide et simple dans une meilleure gestion du carbone et \u00e0 d\u00e9montrer une approche proactive des meilleures pratiques en mati\u00e8re de durabilit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Commencez d\u00e8s aujourd&#8217;hui avec une meilleure mesure des GES<\/h2>\n\n\n\n<p><strong>\u00cates-vous nouveau chez Achilles ?<\/strong> <a href=\"https:\/\/www.achilles.com\/fr\/trouvez-votre-communaute\/\">Rejoignez l&#8217;un de nos r\u00e9seaux<\/a> et ajoutez <a href=\"https:\/\/www.achilles.com\/industry-insights\/introducing-the-carbon-module\/\">le Module Carbone Achilles<\/a> pour obtenir une estimation de vos GES gr\u00e2ce au Calculateur de Carbone Achilles et augmenter vos opportunit\u00e9s commerciales en d\u00e9montrant vos r\u00e9f\u00e9rences en mati\u00e8re de carbone.<\/p>\n\n\n\n<p>D\u00e9couvrez-en plus sur notre suite unique de solutions de <a href=\"https:\/\/www.achilles.com\/fr\/reduction-de-carbone\/\">R\u00e9duction et de Gestion du Carbone<\/a> pour faire des d\u00e9clarations de r\u00e9duction de carbone en toute confiance sur n&#8217;importe quel march\u00e9 \u00e0 chaque \u00e9tape de votre parcours carbone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9quipe ici chez Achilles est ravie de pr\u00e9senter la derni\u00e8re fonctionnalit\u00e9 dans le Module de Gestion du Carbone MyAchilles &#8211; le Calculateur de Carbone Achilles. Notre nouvel outil de Calculateur de Carbone est con\u00e7u pour permettre aux organisations de capturer leurs donn\u00e9es d&#8217;\u00e9missions de gaz \u00e0 effet de serre (GES) et de les partager avec [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":40299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","wds_primary_category":3963,"wds_primary_industry_tax":0,"wds_primary_topic_tax":0,"wds_primary_post_region_tax":0,"footnotes":""},"categories":[3963,8783],"tags":[8804,4340,4642,3998],"industry_tax":[4276],"topic_tax":[11038,4186],"post_region_tax":[],"class_list":["post-40553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-fr","category-mises-a-jour-du-produit","tag-carbon-reduce-fr","tag-chaine-dapprovisionnement","tag-reduction-du-carbone","tag-supply-chain-management-fr","industry_tax-tous-fr","topic_tax-durabilite","topic_tax-reduction-des-emissions-de-carbone"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/posts\/40553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/comments?post=40553"}],"version-history":[{"count":0,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/posts\/40553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/media\/40299"}],"wp:attachment":[{"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/media?parent=40553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/categories?post=40553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/tags?post=40553"},{"taxonomy":"industry_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/industry_tax?post=40553"},{"taxonomy":"topic_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/topic_tax?post=40553"},{"taxonomy":"post_region_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/fr\/wp-json\/wp\/v2\/post_region_tax?post=40553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}