{"id":77180,"date":"2025-07-28T08:30:36","date_gmt":"2025-07-28T07:30:36","guid":{"rendered":"https:\/\/www.achilles.com\/?p=77180"},"modified":"2025-07-29T15:25:01","modified_gmt":"2025-07-29T14:25:01","slug":"mutuality-schliesst-sich-der-achilles-community-an-um-das-lieferantenmanagement-zu-digitalisieren-und-sein-risikokontrollmodell-zu-staerken","status":"publish","type":"post","link":"https:\/\/www.achilles.com\/de\/mutuality-schliest-sich-der-achilles-community-an-um-das-lieferantenmanagement-zu-digitalisieren-und-sein-risikokontrollmodell-zu-starken\/","title":{"rendered":"Mutuality schlie\u00dft sich der Achilles-Community an, um das Lieferantenmanagement zu digitalisieren und sein Risikokontrollmodell zu st\u00e4rken"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.mutualidad.com\/\">Mutualidad<\/a>, eine gemeinn\u00fctzige Versicherungsgesellschaft, die Fachleuten und ihren Familien L\u00f6sungen zur Deckung ihres gesamten Renten- und Sparbedarfs anbietet, ist eine Partnerschaft mit Achilles eingegangen, um ein umfassendes Genehmigungs- und Risikomanagementsystem in ihrer Lieferkette zu implementieren.<\/p>\n\n<p class=\"wp-block-paragraph\">Mit dieser Zusammenarbeit unternimmt die Organisation einen wichtigen Schritt in Richtung Digitalisierung und versucht, die R\u00fcckverfolgbarkeit, die betriebliche Effizienz und die Einhaltung bew\u00e4hrter Verfahren in einem zunehmend anspruchsvollen regulatorischen Umfeld zu verbessern.<\/p>\n\n<p class=\"wp-block-paragraph\">Die Achilles-L\u00f6sung erm\u00f6glicht es Mutualidad, auf validierte Informationen \u00fcber seine Lieferanten zuzugreifen, die Dokumentation zentral zu verwalten, Risikowarnungen in Echtzeit zu erhalten und \u00fcber Schl\u00fcsselindikatoren f\u00fcr die Entscheidungsfindung zu verf\u00fcgen.<\/p>\n\n<p class=\"wp-block-paragraph\">Mutualidad optimiert nicht nur das Management seiner Lieferkette, sondern schlie\u00dft sich auch der Gemeinschaft von mehr als 50 Einkaufsunternehmen in S\u00fcdeuropa an, die Teil des Achilles-\u00d6kosystems sind. In diesem kollaborativen Raum werden Erfahrungen ausgetauscht, verantwortungsvolle Praktiken gef\u00f6rdert und der Fokus auf Transparenz, Ethik und Nachhaltigkeit in der Beziehung zu den Lieferanten verst\u00e4rkt. <\/p>\n\n<p class=\"wp-block-paragraph\">&#8222;Wir bei Mutualidad sind bestrebt, die gleichen Prinzipien der Transparenz, Strenge und Voraussicht, die uns auszeichnen, auch auf die Verwaltung unserer Lieferanten anzuwenden. Die Zusammenarbeit mit Achilles wird es uns erm\u00f6glichen, ein robustes und digitales Modell zu etablieren, um auf diesem Weg voranzukommen&#8220;, sagt <a href=\"https:\/\/www.linkedin.com\/in\/sonia-gonz%C3%A1lez-garc%C3%ADa-a7695b121\/\">Sonia Gonz\u00e1lez<\/a>, Leiterin der Einkaufsabteilung.<\/p>\n\n<p class=\"wp-block-paragraph\">&#8222;Die \u00dcbernahme von Mutualidad verst\u00e4rkt den Trend zu einem proaktiveren und digitalen Lieferantenmanagement, das sich an ESG-Standards orientiert. Es ist eine Freude, ein so engagiertes Unternehmen bei diesem Transformationsprozess zu begleiten, in einem kollaborativen \u00d6kosystem, das Transparenz und gute Praktiken f\u00f6rdert&#8220;, sagt Eva Lezcano, Regional Director Southern Europe bei Achilles.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00dcber Achilles<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Achilles hilft Organisationen auf der ganzen Welt, nachhaltigere, sicherere und widerstandsf\u00e4higere Lieferketten aufzubauen, indem es K\u00e4ufer mit bewerteten Lieferanten in allen Branchen und Regionen zusammenbringt. Mit \u00fcber 30 Jahren Erfahrung erm\u00f6glicht Achilles Unternehmen, Risiken in Echtzeit zu identifizieren, zu mindern und zu \u00fcberwachen, Vorschriften wie CSDDD und CSRD einzuhalten und effektive Due-Diligence-Prozesse einzurichten. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Kontakt zur Presse<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Irina Sigler, Leiterin Marketing SEU &amp; LATAM<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:Irina.sigler@achilles.com\">Irina.sigler@achilles.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mutualidad, eine gemeinn\u00fctzige Versicherungsgesellschaft, die Fachleuten und ihren Familien L\u00f6sungen zur Deckung ihres gesamten Renten- und Sparbedarfs anbietet, ist eine Partnerschaft mit Achilles eingegangen, um ein umfassendes Genehmigungs- und Risikomanagementsystem in ihrer Lieferkette zu implementieren. Mit dieser Zusammenarbeit unternimmt die Organisation einen wichtigen Schritt in Richtung Digitalisierung und versucht, die R\u00fcckverfolgbarkeit, die betriebliche Effizienz und [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":64228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","wds_primary_category":0,"wds_primary_industry_tax":0,"wds_primary_topic_tax":0,"wds_primary_post_region_tax":0,"footnotes":""},"categories":[7,4281],"tags":[7609],"industry_tax":[4054],"topic_tax":[11094],"post_region_tax":[12478,12483,12479,12482,12481,12480],"class_list":["post-77180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einblicke-branche","category-pressemitteilung-de","tag-value-chain-impact-de","industry_tax-bankwesen-und-finanzen-de","topic_tax-lieferkette-de","post_region_tax-englisch-au","post_region_tax-englisch-ca","post_region_tax-englisch-in","post_region_tax-englisch-mea","post_region_tax-englisch-uki","post_region_tax-englisch-us"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/posts\/77180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/comments?post=77180"}],"version-history":[{"count":0,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/posts\/77180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/media\/64228"}],"wp:attachment":[{"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/media?parent=77180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/categories?post=77180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/tags?post=77180"},{"taxonomy":"industry_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/industry_tax?post=77180"},{"taxonomy":"topic_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/topic_tax?post=77180"},{"taxonomy":"post_region_tax","embeddable":true,"href":"https:\/\/www.achilles.com\/de\/wp-json\/wp\/v2\/post_region_tax?post=77180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}